{"id":948,"date":"2010-06-02T01:33:58","date_gmt":"2010-06-01T16:33:58","guid":{"rendered":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/?page_id=948"},"modified":"2010-06-02T01:33:58","modified_gmt":"2010-06-01T16:33:58","slug":"f-35-%e6%ad%bb%e3%81%ae%e5%bd%b1%e3%81%9b%e3%81%be%e3%82%8bg1%e5%8f%b7","status":"publish","type":"page","link":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/%e5%90%84%e8%a9%b1%e5%88%a5%e3%83%a1%e3%83%a2%ef%bc%88%e3%82%b3%e3%83%a1%e3%83%b3%e3%83%88ok%ef%bc%89\/f-35-%e6%ad%bb%e3%81%ae%e5%bd%b1%e3%81%9b%e3%81%be%e3%82%8bg1%e5%8f%b7\/","title":{"rendered":"F-35 \u6b7b\u306e\u5f71\u305b\u307e\u308bG1\u53f7"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":551,"menu_order":335,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-948","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/comments?post=948"}],"version-history":[{"count":1,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/948\/revisions"}],"predecessor-version":[{"id":949,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/948\/revisions\/949"}],"up":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/551"}],"wp:attachment":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/media?parent=948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}