{"id":930,"date":"2010-06-02T01:30:45","date_gmt":"2010-06-01T16:30:45","guid":{"rendered":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/?page_id=930"},"modified":"2010-06-02T01:30:45","modified_gmt":"2010-06-01T16:30:45","slug":"f-25-%e5%9c%b0%e7%8d%84%e3%81%ae%e3%82%b9%e3%82%ab%e3%82%a4%e3%83%a9%e3%82%a4%e3%83%80%e3%83%bc","status":"publish","type":"page","link":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/%e5%90%84%e8%a9%b1%e5%88%a5%e3%83%a1%e3%83%a2%ef%bc%88%e3%82%b3%e3%83%a1%e3%83%b3%e3%83%88ok%ef%bc%89\/f-25-%e5%9c%b0%e7%8d%84%e3%81%ae%e3%82%b9%e3%82%ab%e3%82%a4%e3%83%a9%e3%82%a4%e3%83%80%e3%83%bc\/","title":{"rendered":"F-25 \u5730\u7344\u306e\u30b9\u30ab\u30a4\u30e9\u30a4\u30c0\u30fc"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":551,"menu_order":325,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-930","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/comments?post=930"}],"version-history":[{"count":1,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/930\/revisions"}],"predecessor-version":[{"id":931,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/930\/revisions\/931"}],"up":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/551"}],"wp:attachment":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/media?parent=930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}