{"id":888,"date":"2010-06-02T01:21:58","date_gmt":"2010-06-01T16:21:58","guid":{"rendered":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/?page_id=888"},"modified":"2010-06-02T01:21:58","modified_gmt":"2010-06-01T16:21:58","slug":"f-04-%e3%82%a2%e3%82%a4%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3%e3%83%9e%e3%83%b3%e3%83%89%e3%81%ae%e6%8c%91%e6%88%a6","status":"publish","type":"page","link":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/%e5%90%84%e8%a9%b1%e5%88%a5%e3%83%a1%e3%83%a2%ef%bc%88%e3%82%b3%e3%83%a1%e3%83%b3%e3%83%88ok%ef%bc%89\/f-04-%e3%82%a2%e3%82%a4%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3%e3%83%9e%e3%83%b3%e3%83%89%e3%81%ae%e6%8c%91%e6%88%a6\/","title":{"rendered":"F-04 \u30a2\u30a4\u30a2\u30f3\u30fb\u30b3\u30de\u30f3\u30c9\u306e\u6311\u6226"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":551,"menu_order":304,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-888","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/comments?post=888"}],"version-history":[{"count":1,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/888\/revisions"}],"predecessor-version":[{"id":889,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/888\/revisions\/889"}],"up":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/551"}],"wp:attachment":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/media?parent=888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}