{"id":863,"date":"2010-06-02T01:16:08","date_gmt":"2010-06-01T16:16:08","guid":{"rendered":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/?page_id=863"},"modified":"2010-06-02T01:16:08","modified_gmt":"2010-06-01T16:16:08","slug":"ii-44-%e3%81%9f%e3%81%9f%e3%81%91%ef%bc%81%e9%82%aa%e6%82%aa%e3%81%ae%e7%81%ab%e6%98%9f%e5%9f%ba%e5%9c%b0","status":"publish","type":"page","link":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/%e5%90%84%e8%a9%b1%e5%88%a5%e3%83%a1%e3%83%a2%ef%bc%88%e3%82%b3%e3%83%a1%e3%83%b3%e3%83%88ok%ef%bc%89\/ii-44-%e3%81%9f%e3%81%9f%e3%81%91%ef%bc%81%e9%82%aa%e6%82%aa%e3%81%ae%e7%81%ab%e6%98%9f%e5%9f%ba%e5%9c%b0\/","title":{"rendered":"II-44 \u305f\u305f\u3051\uff01\u90aa\u60aa\u306e\u706b\u661f\u57fa\u5730"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":551,"menu_order":244,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-863","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/comments?post=863"}],"version-history":[{"count":1,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/863\/revisions"}],"predecessor-version":[{"id":864,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/863\/revisions\/864"}],"up":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/551"}],"wp:attachment":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/media?parent=863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}