{"id":851,"date":"2010-06-02T01:13:28","date_gmt":"2010-06-01T16:13:28","guid":{"rendered":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/?page_id=851"},"modified":"2010-06-02T01:13:28","modified_gmt":"2010-06-01T16:13:28","slug":"ii-38-%e9%9b%bb%e7%a3%81%e3%83%a1%e3%82%ab%e9%89%84%e9%ad%94%e7%ab%9c","status":"publish","type":"page","link":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/%e5%90%84%e8%a9%b1%e5%88%a5%e3%83%a1%e3%83%a2%ef%bc%88%e3%82%b3%e3%83%a1%e3%83%b3%e3%83%88ok%ef%bc%89\/ii-38-%e9%9b%bb%e7%a3%81%e3%83%a1%e3%82%ab%e9%89%84%e9%ad%94%e7%ab%9c\/","title":{"rendered":"II-38 \u96fb\u78c1\u30e1\u30ab\u9244\u9b54\u7adc"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":551,"menu_order":238,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-851","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/comments?post=851"}],"version-history":[{"count":1,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/851\/revisions"}],"predecessor-version":[{"id":852,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/851\/revisions\/852"}],"up":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/551"}],"wp:attachment":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/media?parent=851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}