{"id":836,"date":"2010-06-02T01:10:55","date_gmt":"2010-06-01T16:10:55","guid":{"rendered":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/?page_id=836"},"modified":"2010-07-05T03:33:13","modified_gmt":"2010-07-04T18:33:13","slug":"ii-31-%e6%92%83%e5%a2%9c%e3%81%95%e3%82%8c%e3%81%9f%e5%a4%a7%e9%b7%b2","status":"publish","type":"page","link":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/%e5%90%84%e8%a9%b1%e5%88%a5%e3%83%a1%e3%83%a2%ef%bc%88%e3%82%b3%e3%83%a1%e3%83%b3%e3%83%88ok%ef%bc%89\/ii-31-%e6%92%83%e5%a2%9c%e3%81%95%e3%82%8c%e3%81%9f%e5%a4%a7%e9%b7%b2\/","title":{"rendered":"II-31 \u6483\u589c\u3055\u308c\u305f\u5927\u9df2"},"content":{"rendered":"<p><a href=\"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/2010\/04\/18\/\u3068\u308a\u3042\u3048\u305a\u3044\u3063\u307a\u3093\u89e6\u3063\u3066\u307f\u305f\u3044\u2026\u2026\uff08ii-31\u8a71\uff09\/\" target=\"_blank\">\u3068\u308a\u3042\u3048\u305a\u3044\u3063\u307a\u3093\u89e6\u3063\u3066\u307f\u305f\u3044\u2026\u2026\uff08II 31\u8a71\uff09<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u3068\u308a\u3042\u3048\u305a\u3044\u3063\u307a\u3093\u89e6\u3063\u3066\u307f\u305f\u3044\u2026\u2026\uff08II 31\u8a71\uff09<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":551,"menu_order":231,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-836","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/comments?post=836"}],"version-history":[{"count":3,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/836\/revisions"}],"predecessor-version":[{"id":1656,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/836\/revisions\/1656"}],"up":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/551"}],"wp:attachment":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/media?parent=836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}