{"id":775,"date":"2010-06-02T00:45:13","date_gmt":"2010-06-01T15:45:13","guid":{"rendered":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/%e5%90%84%e8%a9%b1%e5%88%a5%e3%83%a1%e3%83%a2%ef%bc%88%e6%ba%96%e5%82%99%e4%b8%ad%ef%bc%89\/ii-03-%e5%9c%b0%e7%8d%84%e3%81%ae%e3%83%96%e3%83%a9%e3%83%83%e3%82%af%e3%83%8a%e3%82%a4%e3%83%84\/"},"modified":"2010-06-02T00:45:13","modified_gmt":"2010-06-01T15:45:13","slug":"ii-03-%e5%9c%b0%e7%8d%84%e3%81%ae%e3%83%96%e3%83%a9%e3%83%83%e3%82%af%e3%83%8a%e3%82%a4%e3%83%84","status":"publish","type":"page","link":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/%e5%90%84%e8%a9%b1%e5%88%a5%e3%83%a1%e3%83%a2%ef%bc%88%e3%82%b3%e3%83%a1%e3%83%b3%e3%83%88ok%ef%bc%89\/ii-03-%e5%9c%b0%e7%8d%84%e3%81%ae%e3%83%96%e3%83%a9%e3%83%83%e3%82%af%e3%83%8a%e3%82%a4%e3%83%84\/","title":{"rendered":"II-03 \u5730\u7344\u306e\u30d6\u30e9\u30c3\u30af\u30ca\u30a4\u30c4"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":551,"menu_order":203,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-775","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/comments?post=775"}],"version-history":[{"count":0,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/775\/revisions"}],"up":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/551"}],"wp:attachment":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/media?parent=775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}