{"id":774,"date":"2010-06-02T00:44:45","date_gmt":"2010-06-01T15:44:45","guid":{"rendered":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/%e5%90%84%e8%a9%b1%e5%88%a5%e3%83%a1%e3%83%a2%ef%bc%88%e6%ba%96%e5%82%99%e4%b8%ad%ef%bc%89\/ii-02-%e8%ac%8e%e3%81%ae%e7%be%bd%e6%a0%b9%e6%89%8b%e8%a3%8f%e5%89%a3\/"},"modified":"2010-06-02T00:44:45","modified_gmt":"2010-06-01T15:44:45","slug":"ii-02-%e8%ac%8e%e3%81%ae%e7%be%bd%e6%a0%b9%e6%89%8b%e8%a3%8f%e5%89%a3","status":"publish","type":"page","link":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/%e5%90%84%e8%a9%b1%e5%88%a5%e3%83%a1%e3%83%a2%ef%bc%88%e3%82%b3%e3%83%a1%e3%83%b3%e3%83%88ok%ef%bc%89\/ii-02-%e8%ac%8e%e3%81%ae%e7%be%bd%e6%a0%b9%e6%89%8b%e8%a3%8f%e5%89%a3\/","title":{"rendered":"II-02 \u8b0e\u306e\u7fbd\u6839\u624b\u88cf\u5263"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":551,"menu_order":202,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-774","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/comments?post=774"}],"version-history":[{"count":0,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/774\/revisions"}],"up":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/551"}],"wp:attachment":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/media?parent=774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}