{"id":738,"date":"2010-06-02T00:16:52","date_gmt":"2010-06-01T15:16:52","guid":{"rendered":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/%e5%90%84%e8%a9%b1%e5%88%a5%e3%83%a1%e3%83%a2%ef%bc%88%e6%ba%96%e5%82%99%e4%b8%ad%ef%bc%89\/085-g-4%e5%8f%b7%e3%81%af%e3%81%82%e3%81%84%e3%81%a4%e3%81%a0\/"},"modified":"2010-07-05T02:48:16","modified_gmt":"2010-07-04T17:48:16","slug":"085-g-4%e5%8f%b7%e3%81%af%e3%81%82%e3%81%84%e3%81%a4%e3%81%a0","status":"publish","type":"page","link":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/%e5%90%84%e8%a9%b1%e5%88%a5%e3%83%a1%e3%83%a2%ef%bc%88%e3%82%b3%e3%83%a1%e3%83%b3%e3%83%88ok%ef%bc%89\/085-g-4%e5%8f%b7%e3%81%af%e3%81%82%e3%81%84%e3%81%a4%e3%81%a0\/","title":{"rendered":"085 G-4\u53f7\u306f\u3042\u3044\u3064\u3060"},"content":{"rendered":"<p><a href=\"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/2010\/06\/17\/\u7d19\u30c6\u30fc\u30d7\uff08\u521d\u4ee3-85\u8a71\uff09\/\" target=\"_blank\">\u7d19\u30c6\u30fc\u30d7\uff08\u521d\u4ee3 85\u8a71\uff09<\/a><\/p>\n<p>\u5357\u90e8\u535a\u58eb\u306b\u3064\u3044\u3066\u306f\u3001\u5192\u982d\u3001\u767b\u5834\u3059\u308b\u304c\u3001\u53f0\u8a5e\u306f\u306a\u3044\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u7d19\u30c6\u30fc\u30d7\uff08\u521d\u4ee3 85\u8a71\uff09 \u5357\u90e8\u535a\u58eb\u306b\u3064\u3044\u3066\u306f\u3001\u5192\u982d\u3001\u767b\u5834\u3059\u308b\u304c\u3001\u53f0\u8a5e\u306f\u306a\u3044\u3002<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":551,"menu_order":85,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-738","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/comments?post=738"}],"version-history":[{"count":5,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/738\/revisions"}],"predecessor-version":[{"id":1565,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/738\/revisions\/1565"}],"up":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/551"}],"wp:attachment":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/media?parent=738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}