{"id":671,"date":"2010-06-01T23:55:21","date_gmt":"2010-06-01T14:55:21","guid":{"rendered":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/?page_id=671"},"modified":"2010-07-05T03:35:44","modified_gmt":"2010-07-04T18:35:44","slug":"053-%e3%81%95%e3%82%89%e3%81%b0%e3%83%ac%e3%83%83%e3%83%89%e3%82%a4%e3%83%b3%e3%83%91%e3%83%ab%e3%82%b9","status":"publish","type":"page","link":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/%e5%90%84%e8%a9%b1%e5%88%a5%e3%83%a1%e3%83%a2%ef%bc%88%e3%82%b3%e3%83%a1%e3%83%b3%e3%83%88ok%ef%bc%89\/053-%e3%81%95%e3%82%89%e3%81%b0%e3%83%ac%e3%83%83%e3%83%89%e3%82%a4%e3%83%b3%e3%83%91%e3%83%ab%e3%82%b9\/","title":{"rendered":"053 \u3055\u3089\u3070\u30ec\u30c3\u30c9\u30a4\u30f3\u30d1\u30eb\u30b9"},"content":{"rendered":"<p><a href=\"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/2010\/04\/18\/\u5370\u8c61\u7684\u3068\u3044\u3046\u610f\u5473\u3067\u306f\uff11\uff0c\uff12\u3092\u4e89\u3046\u306e\u304c\u3053\u308c\uff0853\u8a71\/\" target=\"_blank\">\u5370\u8c61\u7684\u3068\u3044\u3046\u610f\u5473\u3067\u306f\uff11\uff0c\uff12\u3092\u4e89\u3046\u306e\u304c\u3053\u308c\uff0853\u8a71\uff09<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u5370\u8c61\u7684\u3068\u3044\u3046\u610f\u5473\u3067\u306f\uff11\uff0c\uff12\u3092\u4e89\u3046\u306e\u304c\u3053\u308c\uff0853\u8a71\uff09<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":551,"menu_order":53,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-671","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/comments?post=671"}],"version-history":[{"count":3,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/671\/revisions"}],"predecessor-version":[{"id":1662,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/671\/revisions\/1662"}],"up":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/551"}],"wp:attachment":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/media?parent=671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}