{"id":623,"date":"2010-06-01T23:43:38","date_gmt":"2010-06-01T14:43:38","guid":{"rendered":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/?page_id=623"},"modified":"2010-08-29T19:54:40","modified_gmt":"2010-08-29T10:54:40","slug":"029-%e9%ad%94%e4%ba%ba%e3%82%ae%e3%83%a3%e3%83%a9%e3%83%83%e3%82%af%ef%bd%98","status":"publish","type":"page","link":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/%e5%90%84%e8%a9%b1%e5%88%a5%e3%83%a1%e3%83%a2%ef%bc%88%e3%82%b3%e3%83%a1%e3%83%b3%e3%83%88ok%ef%bc%89\/029-%e9%ad%94%e4%ba%ba%e3%82%ae%e3%83%a3%e3%83%a9%e3%83%83%e3%82%af%ef%bd%98\/","title":{"rendered":"029 \u9b54\u4eba\u30ae\u30e3\u30e9\u30c3\u30af\uff38"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":551,"menu_order":29,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-623","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/comments?post=623"}],"version-history":[{"count":5,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/623\/revisions"}],"predecessor-version":[{"id":2385,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/623\/revisions\/2385"}],"up":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/551"}],"wp:attachment":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/media?parent=623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}