{"id":610,"date":"2010-06-01T23:36:06","date_gmt":"2010-06-01T14:36:06","guid":{"rendered":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/%e5%90%84%e8%a9%b1%e5%88%a5%e3%83%a1%e3%83%a2%ef%bc%88%e6%ba%96%e5%82%99%e4%b8%ad%ef%bc%89\/022-%e7%81%ab%e3%81%ae%e9%b3%a5%e5%af%be%e7%81%ab%e5%96%b0%e3%81%84%e9%b3%a5\/"},"modified":"2010-09-04T00:55:55","modified_gmt":"2010-09-03T15:55:55","slug":"022-%e7%81%ab%e3%81%ae%e9%b3%a5%e5%af%be%e7%81%ab%e5%96%b0%e3%81%84%e9%b3%a5","status":"publish","type":"page","link":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/%e5%90%84%e8%a9%b1%e5%88%a5%e3%83%a1%e3%83%a2%ef%bc%88%e3%82%b3%e3%83%a1%e3%83%b3%e3%83%88ok%ef%bc%89\/022-%e7%81%ab%e3%81%ae%e9%b3%a5%e5%af%be%e7%81%ab%e5%96%b0%e3%81%84%e9%b3%a5\/","title":{"rendered":"022 \u706b\u306e\u9ce5\u5bfe\u706b\u55b0\u3044\u9ce5"},"content":{"rendered":"<h3>\u3010\u95a2\u9023\u30b3\u30e1\u30f3\u30c8\u3011<\/h3>\n<ul>\n<li><a href=\"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/2010\/08\/30\/\u7167\u660e\u306e\u8da3\u5473\u304c\u2026\u2026\uff08\u521d\u4ee3-22\u8a71\uff09\/\" target=\"_blank\">\u7167\u660e\u306e\u8da3\u5473\u304c\u2026\u2026\uff08\u521d\u4ee3 22\u8a71\uff09<\/a><\/li>\n<\/ul>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u3010\u95a2\u9023\u30b3\u30e1\u30f3\u30c8\u3011 \u7167\u660e\u306e\u8da3\u5473\u304c\u2026\u2026\uff08\u521d\u4ee3 22\u8a71\uff09<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":551,"menu_order":22,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-610","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/comments?post=610"}],"version-history":[{"count":2,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/610\/revisions"}],"predecessor-version":[{"id":2450,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/610\/revisions\/2450"}],"up":[{"embeddable":true,"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/pages\/551"}],"wp:attachment":[{"href":"http:\/\/www.frontier-line.org\/K-Nambu-PhD\/wp-json\/wp\/v2\/media?parent=610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}